{"id":8627,"date":"2022-11-22T01:00:00","date_gmt":"2022-11-21T21:00:00","guid":{"rendered":"https:\/\/restonsunis.com\/?p=8627"},"modified":"2022-11-21T07:34:30","modified_gmt":"2022-11-21T03:34:30","slug":"le-sanctuaire-modele-pour-la-priere-jour-2","status":"publish","type":"post","link":"https:\/\/restonsunis.com\/index.php\/2022\/11\/22\/le-sanctuaire-modele-pour-la-priere-jour-2\/","title":{"rendered":"Le Sanctuaire, mod\u00e8le pour la pri\u00e8re &#8211; Jour 2"},"content":{"rendered":"\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio has-medium-font-size\">Le sanctuaire est un mod\u00e8le pour la pri\u00e8re. Des portes du parvis jusqu&#8217;\u00e0 l&#8217;Arche de l&#8217;alliance, c&#8217;est un parcours de communion avec Dieu. Le sanctuaire est une invitation \u00e0 exp\u00e9rimenter la pr\u00e9sence de l&#8217;\u00c9ternel avec et en nous.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-embed-aspect-16-9 wp-has-aspect-ratio has-strong-cyan-color has-text-color has-medium-font-size\"><strong>Voici une suggestion de programme pour aujourd&#8217;hui.<\/strong><\/p>\n\n\n\n<h1 class=\"has-text-align-center wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-heading\">Mardi 22 novembre 2022<\/h1>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/lesportes-1024x260.png\" alt=\"\" class=\"wp-image-8584\" width=\"311\" height=\"79\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/lesportes-1024x260.png 1024w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/lesportes-300x76.png 300w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/lesportes-768x195.png 768w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/lesportes.png 1280w\" sizes=\"auto, (max-width: 311px) 100vw, 311px\" \/><\/figure><\/div>\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">1. Portes du parvis : La louange<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\ud83d\ude4c Louange<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Glorious - Quand Tu poses Ta main\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/db1t4_igoDk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/auteldesholocaustes.png\" alt=\"\" class=\"wp-image-8585\" width=\"118\" height=\"130\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/auteldesholocaustes.png 491w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/auteldesholocaustes-273x300.png 273w\" sizes=\"auto, (max-width: 118px) 100vw, 118px\" \/><\/figure><\/div>\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">2. Autel des holocaustes : La pri\u00e8re de confession<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\ud83d\udcd6  Lecture<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-medium-font-size\">Je t\u2019ai fait conna\u00eetre mon p\u00e9ch\u00e9, je n\u2019ai pas cach\u00e9 mon iniquit\u00e9; j\u2019ai dit: J\u2019avouerai mes transgressions \u00e0 l\u2019Eternel! Et tu as effac\u00e9 la peine de mon p\u00e9ch\u00e9.<\/p>\n<cite>Psaume 32.5<\/cite><\/blockquote>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">\ud83d\ude4f <strong>Pri\u00e8re de confession<\/strong><\/p>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\">\n<li>Adressez \u00e0 l&#8217;\u00c9ternel une pri\u00e8re de confession. Citez les p\u00e9ch\u00e9s que vous avez commis avec l&#8217;assurance de leur pardon : <em>&#8220;Si nous confessons nos p\u00e9ch\u00e9s, il est fid\u00e8le et juste pour nous les pardonner, et pour nous purifier de toute iniquit\u00e9.&#8221; 1 Jn 1.9  <\/em><\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/cuvedairain.png\" alt=\"\" class=\"wp-image-8591\" width=\"134\" height=\"142\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/cuvedairain.png 319w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/cuvedairain-282x300.png 282w\" sizes=\"auto, (max-width: 134px) 100vw, 134px\" \/><\/figure><\/div>\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">3. Cuve d&#8217;airain : Le renouvellement<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\ud83d\ude4f Pri\u00e8re d&#8217;engagement et de renouvellement<\/strong><\/p>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\">\n<li>Priez pour un renouvellement de votre vie d&#8217;engagement, de cons\u00e9cration et de fid\u00e9lit\u00e9 \u00e0 l&#8217;\u00c9ternel, dans les grandes et les moindres choses. Faites silence pour laisser Dieu vous parlez par sa parole.<\/li>\n\n\n\n<li>Identifiez ce que vous aimeriez que Dieu transforme dans votre vie.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/tabledespains.png\" alt=\"\" class=\"wp-image-8592\" width=\"272\" height=\"126\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/tabledespains.png 725w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/tabledespains-300x140.png 300w\" sizes=\"auto, (max-width: 272px) 100vw, 272px\" \/><\/figure><\/div>\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">4. Table des pains : La Parole de Dieu<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\ud83d\udcd6  Lecture<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le Sanctuaire c\u00e9leste avant la chute (1)<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Louez l\u2019Eternel! Louez Dieu dans son sanctuaire! Louez-le dans l\u2019\u00e9tendue, o\u00f9 \u00e9clate sa puissance!<\/p>\n<cite>Psaume 150.1<\/cite><\/blockquote>\n\n\n\n<p class=\"has-medium-font-size\">Apr\u00e8s avoir ordonn\u00e9 \u00e0 Mo\u00efse de construire un sanctuaire (Ex 25.8), Dieu ajoute du m\u00eame souffle : \u00ab Vous ferez le tabernacle et tous ses ustensiles d\u2019apr\u00e8s le mod\u00e8le que je vais te montrer. \u00bb (v. 9) Le terme h\u00e9breu pour \u00ab mod\u00e8le \u00bb implique que le splendide sanctuaire terrestre devait \u00eatre une copie du vaste et glorieux sanctuaire c\u00e9leste (un faible reflet de l\u2019original, \u00e0 vrai dire ; voir He 8.3-5). Selon J\u00e9r\u00e9mie 17.12, le sanctuaire c\u00e9leste existait \u00ab d\u00e8s le commencement \u00bb.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Avant sa chute, l\u2019ange Lucifer occupait le poste de \u00ab ch\u00e9rubin protecteur \u00bb dans ce sanctuaire, \u00ab en \u00c9den, le jardin de Dieu \u00bb, \u00ab sur la sainte montagne de Dieu \u00bb (Ez 28.13,14), appel\u00e9e aussi \u00ab montagne de l\u2019assembl\u00e9e \u00bb (Es 14.13).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Avant de traiter le probl\u00e8me du p\u00e9ch\u00e9, le sanctuaire c\u00e9leste \u00e9tait le lieu o\u00f9 les habitants de l\u2019univers se r\u00e9unissaient pour adorer et louer leur cr\u00e9ateur. Disons-le en termes th\u00e9ologiques : \u00ab Avant la sot\u00e9riologie [le salut], il y avait la doxologie [la louange] ! \u00bb Les \u00c9critures nous r\u00e9v\u00e8lent d\u2019un bout \u00e0 l\u2019autre que ce temple c\u00e9leste est vibrant de louanges, d\u2019adoration, et de v\u00e9n\u00e9ration envers le Roi des rois, m\u00eame en plein c\u0153ur de la r\u00e9solution du probl\u00e8me du p\u00e9ch\u00e9 (voir, par ex., Es 6.1-8 ; Ps 150.1 ; Ap 4.8-11 ; 5.9-14).<\/p>\n\n\n\n<p><em>Richard M. Davidson est professeur d\u2019interpr\u00e9tation de l\u2019Ancien Testament au S\u00e9minaire adventiste de th\u00e9ologie J. N. Andrews, \u00e0 l\u2019Universit\u00e9 Andrews. Extrait de l\u2019article \u201cSanctuaire, vivre en la pr\u00e9sence de Dieu\u201d, AW de mars 2022<\/em><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/chandelierallume.png\" alt=\"\" class=\"wp-image-8601\" width=\"182\" height=\"191\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/chandelierallume.png 358w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/chandelierallume-286x300.png 286w\" sizes=\"auto, (max-width: 182px) 100vw, 182px\" \/><\/figure><\/div>\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">5. Chandelier : Le Saint-Esprit<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\ud83d\ude4f Pri\u00e8re pour le Saint-Esprit<\/strong><\/p>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\">\n<li>Demandez au Saint-Esprit d&#8217;\u00e9clairer le texte et le commentaire que vous venez de lire.<\/li>\n\n\n\n<li>Priez pour l&#8217;effusion du Saint-Esprit.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/auteldesparfums.png\" alt=\"\" class=\"wp-image-8602\" width=\"268\" height=\"138\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/auteldesparfums.png 727w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/auteldesparfums-300x155.png 300w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/><\/figure><\/div>\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">6. Autel des parfums : L&#8217;intercession<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\ud83d\ude4f Sujets de pri\u00e8re<\/strong><\/p>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\">\n<li>Priez pour le renouveau de l&#8217;\u00e9glise adventiste dans le monde et particuli\u00e8rement \u00e0 La R\u00e9union<\/li>\n\n\n\n<li>Priez pour votre \u00e9glise, ses membres et ses responsables<\/li>\n\n\n\n<li>Priez pour vos sujets personnels et les besoins de vos proches et connaissances<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/restonsunis.com\/index.php\/a-votre-ecoute\/\">Transmettre un sujet de pri\u00e8re, un t\u00e9moignage&#8230;<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"has-medium-font-size\"><em>Sujets de pri\u00e8re de l&#8217;\u00e9glise mondiale :<\/em><\/p>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\">\n<li>Priez pour que Dieu continue \u00e0 faire grandir l\u2019\u00e9glise en Colombie. Priez pour que les croyants partagent avec joie et exercent leur minist\u00e8re aupr\u00e8s de ceux qui les entourent.<\/li>\n\n\n\n<li>Priez pour les plans en cours d\u2019\u00e9laboration concernant les efforts d\u2019\u00e9vang\u00e9lisation en Europe pour 2023. Priez pour que Dieu ouvre d\u00e8s maintenant des portes appropri\u00e9es.<\/li>\n\n\n\n<li>Priez pour nos pasteurs, conjoints de pasteurs, anciens, conjoints d\u2019anciens, diacres et diaconesses dans le monde entier. Priez pour que Dieu les remplisse du Saint-Esprit et les fortifie dans le minist\u00e8re.<\/li>\n\n\n\n<li>Priez pour la division Euro-Asie (ESD) et ceux qui tentent d\u2019aider les migrants en leur fournissant un endroit o\u00f9 dormir, de la nourriture et des v\u00eatements. Priez pour les enfants des migrants alors qu\u2019on leur enseigne les fondements bibliques.<\/li>\n\n\n\n<li>Priez pour les membres de notre \u00e9glise en Ukraine et en Russie. Priez pour que le conflit en Ukraine prenne fin. Beaucoup de membres de notre \u00e9glise souffrent. Priez tout particuli\u00e8rement pour nos pasteurs et nos anciens, ainsi que leurs familles, qui tentent de r\u00e9pondre \u00e0 de nombreux besoins.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/archedelalliance-1024x484.png\" alt=\"\" class=\"wp-image-8603\" width=\"331\" height=\"156\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/archedelalliance-1024x484.png 1024w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/archedelalliance-300x142.png 300w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/archedelalliance-768x363.png 768w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/archedelalliance.png 1038w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/><\/figure><\/div>\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">7. Autel de l&#8217;alliance : Rester en communion avec Dieu<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\ud83d\udcd6  Lecture<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-medium-font-size\">Heureux l\u2019homme qui ne marche pas selon le conseil des m\u00e9chants, qui ne s\u2019arr\u00eate pas sur la voie des p\u00e9cheurs, et qui ne s\u2019assied pas en compagnie des moqueurs, mais qui trouve son plaisir dans la loi de l\u2019Eternel, et qui la m\u00e9dite jour et nuit! Il est comme un arbre plant\u00e9 pr\u00e8s d\u2019un courant d\u2019eau, qui donne son fruit en sa saison, et dont le feuillage ne se fl\u00e9trit point : Tout ce qu\u2019il fait lui r\u00e9ussit.<\/p>\n<cite>Psaume 1.1-4<\/cite><\/blockquote>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">\ud83c\udfb5 <strong>M\u00e9ditation musicale<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"cet air que je respire &quot; piano &quot;\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/lrgTTM_yRcI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center\"><strong>\ud83d\ude4f B\u00e9n\u00e9diction<\/strong><\/p>\n\n\n\n<p>Qu\u2019il te donne ce que ton c\u0153ur d\u00e9sire<br>et qu\u2019il accomplisse tous tes projets!<\/p>\n<cite>Psaume 20:5<\/cite><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Le sanctuaire est un mod\u00e8le pour la pri\u00e8re. Des portes du parvis jusqu&#8217;\u00e0 l&#8217;Arche de l&#8217;alliance, c&#8217;est&hellip;<\/p>\n","protected":false},"author":1,"featured_media":8621,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[140],"tags":[],"class_list":["post-8627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-sanctuaire-un-modele-pour-la-priere"],"_links":{"self":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts\/8627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/comments?post=8627"}],"version-history":[{"count":11,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts\/8627\/revisions"}],"predecessor-version":[{"id":8660,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts\/8627\/revisions\/8660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/media\/8621"}],"wp:attachment":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/media?parent=8627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/categories?post=8627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/tags?post=8627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}