{"id":8794,"date":"2022-12-10T13:00:00","date_gmt":"2022-12-10T09:00:00","guid":{"rendered":"https:\/\/restonsunis.com\/?p=8794"},"modified":"2022-12-10T16:53:24","modified_gmt":"2022-12-10T12:53:24","slug":"eds-l12-la-vision-biblique-du-monde","status":"publish","type":"post","link":"https:\/\/restonsunis.com\/index.php\/2022\/12\/10\/eds-l12-la-vision-biblique-du-monde\/","title":{"rendered":"EDS-L12 : La vision biblique du monde"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Introduction de la le\u00e7on<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">SABBAT APR\u00c8S-MIDI<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Lecture de la semaine: Luc 2:52; Matthieu 4:23; 1 Corinthiens 6:19, 20; Ps. 24:3, 4; Actes 8:4-24; 1 Jean 3:1-3.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Verset \u00e0 m\u00e9moriser: \u00ab Que le Dieu de paix vous sanctifie lui-m\u00eame tout entiers, et que tout votre \u00eatre, l\u2019esprit, l\u2019\u00e2me et le corps, soit conserv\u00e9 irr\u00e9pr\u00e9hensible, lors de l\u2019av\u00e8nement de notre Seigneur J\u00e9sus Christ! \u00bb (1 Thessaloniciens 5:23, LSG).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Le livre de l\u2019Apocalypse parle de deux \u00ab mondialisations \u00bb avant la seconde venue de Christ. Apocalypse 13 d\u00e9crit la mondialisation de l\u2019erreur, quand \u00ab toute la terre \u00bb s\u2019\u00e9merveillera et suivra la b\u00eate de la mer (Apocalypse 13:3, 7, 8, 12, 16, LSG). Apocalypse 14 met en lumi\u00e8re la mondialisation de la v\u00e9rit\u00e9, lorsque l\u2019\u00ab \u00e9vangile \u00e9ternel \u00bb sera pr\u00each\u00e9 \u00ab \u00e0 toute nation, \u00e0 toute tribu, \u00e0 toute langue, et \u00e0 tout peuple \u00bb (Apocalypse 14:6, 7, LSG). Pendant ces \u00ab temps difficiles \u00bb (2 Timoth\u00e9e 3:1, LSG), \u00ab tout vent de doctrine \u00bb soufflera (Eph. 4:14, LSG) et les gens \u00ab d\u00e9tourneront l\u2019oreille de la v\u00e9rit\u00e9, et se tourneront vers les fables \u00bb (2 Timoth\u00e9e 4:4, LSG). \u00ab Deux grandes erreurs: l\u2019immortalit\u00e9 de l\u2019\u00e2me et la saintet\u00e9 du dimanche vont \u00eatre les moyens par lesquels Satan fera tomber le monde dans ses pi\u00e8ges. Tandis que la premi\u00e8re jette les bases du spiritisme, la seconde \u00e9tablit un lien de sympathie avec Rome. \u00bb Ellen G. White, La trag\u00e9die des si\u00e8cles, p. 519.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Jusqu\u2019\u00e0 ce que ces \u00e9v\u00e8nements finaux se produisent, nous devons rester fermes dans notre croyance en toute la v\u00e9rit\u00e9 que nous avons, qui inclut la nature de l\u2019humanit\u00e9 et de la mort, alors que nous cherchons \u00e0 \u00eatre guid\u00e9s par le Saint-Esprit dans le but d\u2019\u00eatre pr\u00eats pour l\u2019apparition glorieuse de Christ.<br>\u00c9tudiez cette le\u00e7on pour le sabbat 17 d\u00e9cembre.<\/p>\n\n\n\n<div class=\"wp-block-cover is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-cyan-bluish-gray-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading\">SOMMAIRE DE L&#8217;ARTICLE<\/h2>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"#lecon\"><strong>Le\u00e7on compl\u00e8te + moniteur<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"#video\">Commentaires vid\u00e9os<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"#complement\">Compl\u00e9ments \u00e0 t\u00e9l\u00e9charger<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"lecon\">Le\u00e7on compl\u00e8te<\/h2>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/12\/ABSG-22-Q4-FR-L12-T.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 ABSG-22-Q4-FR-L12-T.\"><\/object><a id=\"wp-block-file--media-89b4993d-6d5e-4ee7-ad56-54be26b493c3\" href=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/12\/ABSG-22-Q4-FR-L12-T.pdf\">ABSG-22-Q4-FR-L12-T<\/a><a href=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/12\/ABSG-22-Q4-FR-L12-T.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-89b4993d-6d5e-4ee7-ad56-54be26b493c3\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-black-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"video\">Commentaires vid\u00e9os<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Espoir M\u00e9dias \u2022 3DS<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"LA VISION BIBLIQUE DU MOND | 3DS Le\u00e7on 12 | Avec Nicolas, Val\u00e9ry et \u00c9ric\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/jGFSruAWZx8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Eglise Saint-Georges \u2022 \u00c9cole du Sabbat<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La vision biblique du monde (Le\u00e7on 12, 4e Trimestre 2022)\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/Errn2G4UBtY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">FFN \u2022 \u00c9tude de l&#8217;\u00c9cole du Sabbat<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La vision biblique du monde - E\u0301tude de l&#039;e\u0301cole du Sabbat 12 EDS #adventiste ffn\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/ycnj5lersw0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Eglise de Morija \u2022 \u00c9mission Autrement Dit<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"AUTREMENT DIT    La vision biblique du monde 16 12 2022\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/4VBbIke1iPk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-cyan-bluish-gray-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"complement\">Compl\u00e9ments \u00e0 t\u00e9l\u00e9charger<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c0 l&#8217;\u00e9coute du texte<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/alecoutedutexte.png\" alt=\"\" class=\"wp-image-8430\" width=\"185\" height=\"125\" srcset=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/alecoutedutexte.png 406w, https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/alecoutedutexte-300x203.png 300w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" \/><\/figure><\/div>\n\n\n<p>Les feuillets \u00ab \u00c0 l\u2019\u00e9coute du texte \u00bb, qui accompagnent la cat\u00e9ch\u00e8se (EDS) des adultes, sont sous la responsabilit\u00e9 du pasteur&nbsp;Gabriel Gol\u00e9a. Ce mat\u00e9riel, fruit du travail minutieux et attentif d\u2019une \u00e9quipe de b\u00e9n\u00e9voles, est destin\u00e9 \u00e0 \u00e9clairer l\u2019\u00e9tude de la Bible dans le cadre de l\u2019\u00e9cole du sabbat, un outil pratique surtout pour les animateurs en qu\u00eate des nouvelles id\u00e9es, fra\u00eeches pour leurs classes. Site internet : <a href=\"https:\/\/adventiste.org\/bible\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/adventiste.org\/bible\/<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/cloud.eud.adventist.org\/index.php\/s\/6ncrZzamoC8zoNC\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/pdf-logo.png\" alt=\"\" class=\"wp-image-8440\"\/><\/a><figcaption class=\"wp-element-caption\">Le\u00e7on 12<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\">Power Point pour moniteur<\/h3>\n\n\n\n<p>Vous pouvez t\u00e9l\u00e9charger une pr\u00e9sentation PowerPoint de l&#8217;\u00e9cole du sabbat pour aider \u00e0 pr\u00e9parer et pr\u00e9sent\u00e9 la le\u00e7on de cette semaine. Traduit par:&nbsp;Daniel Paez&nbsp;et corrig\u00e9 par des membres de l\u2019\u00e9glise adventistes de Renens, Suisse. Site internet : <a rel=\"noreferrer noopener\" href=\"https:\/\/www.fustero.es\/index_fr.php\" target=\"_blank\">https:\/\/www.fustero.es\/index_fr.php<\/a><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.fustero.es\/descargar.php?id=fr_2022t412_2.pptx\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/microsoft-powerpoint-logo.png\" alt=\"\" class=\"wp-image-8439\"\/><\/a><figcaption class=\"wp-element-caption\">Le\u00e7on 12 : (PowerPoint)<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.fustero.es\/descargar.php?id=fr_2022t412_2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/restonsunis.com\/wp-content\/uploads\/2022\/11\/pdf-logo.png\" alt=\"\" class=\"wp-image-8440\"\/><\/a><figcaption class=\"wp-element-caption\">Le\u00e7on 12 (PDF)<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Introduction de la le\u00e7on SABBAT APR\u00c8S-MIDI Lecture de la semaine: Luc 2:52; Matthieu 4:23; 1 Corinthiens 6:19,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":8294,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[],"class_list":["post-8794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eds-blog"],"_links":{"self":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts\/8794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/comments?post=8794"}],"version-history":[{"count":2,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts\/8794\/revisions"}],"predecessor-version":[{"id":8802,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/posts\/8794\/revisions\/8802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/media\/8294"}],"wp:attachment":[{"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/media?parent=8794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/categories?post=8794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/restonsunis.com\/index.php\/wp-json\/wp\/v2\/tags?post=8794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}